{"id":270,"date":"2015-08-19T09:09:37","date_gmt":"2015-08-19T09:09:37","guid":{"rendered":"http:\/\/www.cssr.news\/spanish\/?p=270"},"modified":"2015-11-19T09:09:47","modified_gmt":"2015-11-19T09:09:47","slug":"4-pedro-pablo-blasucci-1793-1817","status":"publish","type":"post","link":"https:\/\/www.cssr.news\/spanish\/2015\/08\/4-pedro-pablo-blasucci-1793-1817\/","title":{"rendered":"4. Pedro Pablo Blasucci (1793-1817)"},"content":{"rendered":"<p style=\"text-align: justify;\">Nacido el 22 de febrero de 1729 en Ruvo, Italia, profesa el 14 de agosto de 1753. Tras la muerte de san Alfonso es elegido Rector Mayor para los Redentoristas de Sicilia. El 12 de marzo de 1812 es elegido Rector Mayor de todo el Instituto. Muere en Pagani el 13 de junio de 1817.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nacido el 22 de febrero de 1729 en Ruvo, Italia, profesa el 14 de agosto de 1753. Tras la muerte de san Alfonso es elegido Rector Mayor para los Redentoristas de Sicilia. El 12 de marzo de 1812 es elegido Rector Mayor de todo el Instituto. Muere en Pagani el 13 de junio de 1817.<\/p>\n","protected":false},"author":2,"featured_media":271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/posts\/270"}],"collection":[{"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":1,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/posts\/270\/revisions"}],"predecessor-version":[{"id":272,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/posts\/270\/revisions\/272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/media\/271"}],"wp:attachment":[{"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/media?parent=270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/categories?post=270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cssr.news\/spanish\/wp-json\/wp\/v2\/tags?post=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}